{"id":656,"date":"2006-03-04T07:52:25","date_gmt":"2006-03-04T06:52:25","guid":{"rendered":"http:\/\/www.bushido-lubwart.de\/wordpress\/?p=656"},"modified":"2006-03-04T07:52:25","modified_gmt":"2006-03-04T06:52:25","slug":"srd-mitgliederversammlung","status":"publish","type":"post","link":"https:\/\/www.bushido-lubwart.de\/wordpress\/srd-mitgliederversammlung\/","title":{"rendered":"SRD-Mitgliederversammlung"},"content":{"rendered":"<p>An der diesj\u00e4hrigen SRD-Mitgliederversammlung konnte leider kein Vertreter unseres Vereins teilnehmen. Nachdem die beiden Vorstandsmitglieder Maik Hinze und Ralph P. G\u00f6rlach aus dienstlichen Gr\u00fcnden verhindert war, bem\u00fchten wir uns zwar Ersatz zu finden, allerdings geland es nicht in der kurzen Zeit ein Mitglied zu finden, welches Zeit gehabt h\u00e4tte nach Neuruppin zu fahren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>An der diesj\u00e4hrigen SRD-Mitgliederversammlung konnte leider kein Vertreter unseres Vereins teilnehmen. Nachdem die beiden Vorstandsmitglieder Maik Hinze und Ralph P. G\u00f6rlach aus dienstlichen Gr\u00fcnden verhindert war, bem\u00fchten wir uns zwar Ersatz zu finden, allerdings geland es nicht in der kurzen Zeit ein Mitglied zu finden, welches Zeit gehabt h\u00e4tte nach Neuruppin zu fahren.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[143],"tags":[],"class_list":["post-656","post","type-post","status-publish","format-standard","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.bushido-lubwart.de\/wordpress\/wp-json\/wp\/v2\/posts\/656"}],"collection":[{"href":"https:\/\/www.bushido-lubwart.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bushido-lubwart.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bushido-lubwart.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bushido-lubwart.de\/wordpress\/wp-json\/wp\/v2\/comments?post=656"}],"version-history":[{"count":0,"href":"https:\/\/www.bushido-lubwart.de\/wordpress\/wp-json\/wp\/v2\/posts\/656\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.bushido-lubwart.de\/wordpress\/wp-json\/wp\/v2\/media?parent=656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bushido-lubwart.de\/wordpress\/wp-json\/wp\/v2\/categories?post=656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bushido-lubwart.de\/wordpress\/wp-json\/wp\/v2\/tags?post=656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}