{"id":287,"date":"1999-03-15T08:03:48","date_gmt":"1999-03-15T07:03:48","guid":{"rendered":"http:\/\/lubwart.de\/wordpress\/?p=287"},"modified":"1999-03-15T08:03:48","modified_gmt":"1999-03-15T07:03:48","slug":"neuregelungen","status":"publish","type":"post","link":"https:\/\/www.bushido-lubwart.de\/wordpress\/neuregelungen\/","title":{"rendered":"Neuregelungen"},"content":{"rendered":"<p>Die Kosten-, Honorar- und Entgeltordnung wurde wieder einmal kr\u00e4ftig \u00fcberarbeitet. Neuregelungen im \u00dcberblick: Fahrtkosten, Schauk\u00e4sten, Internet.<\/p>\n<p><!--more--><br \/>\nFahrtkosten<\/p>\n<p>Die Fahrtkostenerstattungss\u00e4tze f\u00fcr \u00dcbungsleiter und den Vorstand wurden aufgrund der nunmehr bereits 3. Erh\u00f6hung der Benzinpreise seit der letzten Anpassung durch den Vorstand auf 65 Pfennig je Entfernungskilometer angehoben. Diese Neuregelung tritt ab dem 1. April in Kraft.<\/p>\n<p>Internet<\/p>\n<p>Die Internet-Site des Vereins soll mindestens dreimal j\u00e4hrlich aktualisiert werden.<\/p>\n<p>F\u00fcr im Internet ver\u00f6ffentlichte Artikel gelten ab sofort die gleichen Entgelte wie f\u00fcr die Vereinszeitung:<\/p>\n<p>1. 100 bis 300 Worten 5,00 DM<br \/>\n2. 300 bis 700 Worte 10,00 DM<br \/>\n3. 700 bis 1500 Worte 15,00 DM<br \/>\n4. ab 1500 Worte 20,00 DM.<\/p>\n<p>Die Erfassung handschriftlicher oder mit Maschine geschriebener Texte geht zu Lasten des Autors. Bei manueller Eingabe mindert sich das nach den Nummern 1 bis 4 an den Autor zu zahlende Entgelt um 20 v.H.; wird die Textvorlage in den Computer eingelesen, mindert sich das zu zahlende Entgelt entsprechend um die f\u00fcr das Einscannen von Text zu zahlende Pauschale (1 DM je Seite). Die Entgeltsminderung wird an den Erfasser ausgezahlt.<\/p>\n<p>Ist ein Artikel bereits in der Vereinszeitung ver\u00f6ffentlich, so wird f\u00fcr eine Ver\u00f6ffentlichung im Internet kein Entgelt gezahlt werden. Die ma\u00dfgeblichen Entgelte werden nur einmal ausgezahlt.<\/p>\n<p>F\u00fcr Bilder im Internet wird der Vorgang des Scannens oder Erstellens mit 0,30 DM je Bild abgegolten. Bei digitalen Bildern erh\u00e4lt der Eigent\u00fcmer das entsprechende Entgelt.<\/p>\n<p>F\u00fcr die Erstellung der Internet-Site bzw. deren \u00dcberarbeitung wird ein Entgelt von 5,00 DM je Seite gew\u00e4hrt. Der Anspruch muss gegen\u00fcber dem Vorstand geltend gemacht werden. Dabei sind die jeweiligen Anspruchsgrundlagen detailliert darzulegen.<\/p>\n<p>Schauk\u00e4sten<\/p>\n<p>Schauk\u00e4sten sollen monatlich aktualisiert werden. Hierf\u00fcr wird durch den Verein ein Entgelt von pauschal 4,00 DM je Seite gew\u00e4hrt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Kosten-, Honorar- und Entgeltordnung wurde wieder einmal kr\u00e4ftig \u00fcberarbeitet. Neuregelungen im \u00dcberblick: Fahrtkosten, Schauk\u00e4sten, Internet.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[143],"tags":[],"class_list":["post-287","post","type-post","status-publish","format-standard","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.bushido-lubwart.de\/wordpress\/wp-json\/wp\/v2\/posts\/287"}],"collection":[{"href":"https:\/\/www.bushido-lubwart.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bushido-lubwart.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bushido-lubwart.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bushido-lubwart.de\/wordpress\/wp-json\/wp\/v2\/comments?post=287"}],"version-history":[{"count":1,"href":"https:\/\/www.bushido-lubwart.de\/wordpress\/wp-json\/wp\/v2\/posts\/287\/revisions"}],"predecessor-version":[{"id":2268,"href":"https:\/\/www.bushido-lubwart.de\/wordpress\/wp-json\/wp\/v2\/posts\/287\/revisions\/2268"}],"wp:attachment":[{"href":"https:\/\/www.bushido-lubwart.de\/wordpress\/wp-json\/wp\/v2\/media?parent=287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bushido-lubwart.de\/wordpress\/wp-json\/wp\/v2\/categories?post=287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bushido-lubwart.de\/wordpress\/wp-json\/wp\/v2\/tags?post=287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}